{"id":7828,"date":"2024-03-01T02:10:03","date_gmt":"2024-03-01T02:10:03","guid":{"rendered":"https:\/\/www.costulessseguros.com\/blog\/?p=7828"},"modified":"2025-07-01T21:20:34","modified_gmt":"2025-07-01T21:20:34","slug":"derechos-de-los-inquilinos-en-california-guia-actualizada","status":"publish","type":"post","link":"https:\/\/www.costulessseguros.com\/blog\/derechos-de-los-inquilinos-en-california-guia-actualizada\/","title":{"rendered":"Derechos de los inquilinos en California: Gu\u00eda actualizada\u00a0"},"content":{"rendered":"\n<p>Si est\u00e1s por rentar es importante que conozcas los <strong>derechos de los inquilinos<\/strong> en California para evitar abusos de parte del propietario. Seg\u00fan las leyes del estado sobre propietarios e inquilinos, al rentar tienes derecho a:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Alquilar viviendas seguras y habitables.&nbsp;<\/li>\n\n\n\n<li>Demandar al propietario por represalias.&nbsp;<\/li>\n\n\n\n<li>Retener el alquiler por no prestar servicios esenciales.&nbsp;<\/li>\n\n\n\n<li>Recuperar los honorarios de los abogados y mucho m\u00e1s.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Por ejemplo, la Ley de Protecci\u00f3n de inquilinos de 2019, exige que los propietarios tengan una raz\u00f3n justificada para desalojar a los inquilinos. Por ejemplo, por falta de pago (solo si el inquilino ha permanecido 12 meses en la vivienda).&nbsp;<\/p>\n\n\n\n<p>Uno de los derechos recientes que regir\u00e1 a partir del 1 de Julio de 2024, es que <strong>el dep\u00f3sito de seguridad se limitar\u00e1 a un mes de alquiler<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:16px\"><strong>\u00a1Sigue leyendo para conocer m\u00e1s detalles sobre los derechos de los inquilinos en California!<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-3.jpg\" alt=\"Pareja relajada por conocer los derechos de los inquilinos en California\" class=\"wp-image-7832\" srcset=\"https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-3.jpg 1000w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-3-300x200.jpg 300w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-3-768x512.jpg 768w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-3-390x260.jpg 390w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-3-270x180.jpg 270w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-3-780x520.jpg 780w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-3-540x360.jpg 540w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-3-280x187.jpg 280w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-3-240x160.jpg 240w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-3-560x374.jpg 560w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-3-480x320.jpg 480w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-3-720x480.jpg 720w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Lista de los derechos de los inquilinos en California&nbsp;&nbsp;<\/h2>\n\n\n\n<p>A continuaci\u00f3n, te presentamos una lista general de la ley de California sobre propietarios e inquilinos, que explica los derechos que tienen los inquilinos en un contrato, conoce cada uno de ellos y toma nota:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Derecho a una vivienda habitable&nbsp;<\/h3>\n\n\n\n<p>Una unidad de alquiler debe ser \u201chabitable\u201d, lo que significa que es apta para personas y cumple sustancialmente con los c\u00f3digos de salud y construcci\u00f3n estatales y locales que afectan considerablemente la salud y seguridad de los inquilinos. Hay muchos tipos de defectos que podr\u00edan hacer que una unidad de alquiler no sea habitable. Algunos ejemplos incluyen:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Impermeabilizaci\u00f3n inadecuada&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No hay agua corriente caliente o fr\u00eda&nbsp;<\/li>\n\n\n\n<li>Un sistema el\u00e9ctrico, incluyendo iluminaci\u00f3n, alambres y equipo, que no est\u00e1 en buen estado de funcionamiento&nbsp;<\/li>\n\n\n\n<li>No hay calefacci\u00f3n&nbsp;<\/li>\n\n\n\n<li>Condiciones antihigi\u00e9nicas que pueden incluir una infestaci\u00f3n de plagas como ratas, ratones, cucarachas o chinches&nbsp;<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Retenci\u00f3n del alquiler&nbsp;<\/h3>\n\n\n\n<p>Seg\u00fan el &#8220;Remedio de Reparaci\u00f3n y Deducci\u00f3n&#8221;, los inquilinos pueden retener parcialmente los pagos si el propietario no hace o se niega a hacer una reparaci\u00f3n importante en la propiedad.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tiempo de aviso por aumento del alquiler&nbsp;<\/h3>\n\n\n\n<p>Los <strong>propietarios en California pueden aumentar el precio del alquiler una vez cada 12 meses<\/strong>. Por lo general, estos deben avisar al inquilino con al menos 30 d\u00edas de antelaci\u00f3n. Sin embargo, si el aumento es superior al 10% de la cantidad m\u00e1s baja pagada durante los \u00faltimos 12 meses, deben avisar con al menos 60 d\u00edas de antelaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>Es importante que sepas que el due\u00f1o de la propiedad no puede subir el precio del alquiler para tomar represalias o como medida discriminatoria. As\u00ed que puedes buscar asesoramiento legal y demandarles.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Dep\u00f3sito de garant\u00eda&nbsp;<\/h3>\n\n\n\n<p>Seg\u00fan la ley, se establece que los<strong> dep\u00f3sitos de seguridad no son obligatorios, pero se recomiendan para evitar problemas futuros<\/strong>. Estos dep\u00f3sitos pueden ser iguales a un mes de alquiler, dos meses de alquiler o tres meses de alquiler (para departamentos amueblados).&nbsp;<\/p>\n\n\n\n<p>Por otro lado, los propietarios est\u00e1n obligados a devolver las fianzas en un plazo de 21 d\u00edas desde que el inquilino se muda. A continuaci\u00f3n, listamos los casos en los que el propietario puede retener la devoluci\u00f3n de la fianza:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cubrir el impago del alquiler.&nbsp;<\/li>\n\n\n\n<li>Gastos de limpieza o reparaciones derivadas de un desgaste extremo.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><strong>Si el propietario se niega a devolver la fianza en un plazo de 21 d\u00edas, puede ser sancionado<\/strong>. Y este no debe deducir otros gastos de la fianza adem\u00e1s del alquiler impagado o los gastos por da\u00f1os.&nbsp;<\/p>\n\n\n\n<p><strong>Nota:<\/strong> Los propietarios que deduzcan gastos de la fianza deben facilitar una lista detallada de las reparaciones que hayan hecho con esos fondos.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Rescisi\u00f3n del contrato de alquiler&nbsp;<\/h3>\n\n\n\n<p>Seg\u00fan la legislaci\u00f3n, las dos partes implicadas en un contrato de alquiler pueden rescindir el contrato una vez llegado su vencimiento, es decir dejar sin efecto el contrato. A continuaci\u00f3n, se indica el plazo de preaviso que deben dar inquilinos y propietarios:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Arrendamientos semanales: Con siete d\u00edas de antelaci\u00f3n.&nbsp;<\/li>\n\n\n\n<li>Arrendamientos mensuales: 30 d\u00edas de preaviso.&nbsp;<\/li>\n\n\n\n<li>Trimestral: No especificado.&nbsp;<\/li>\n\n\n\n<li>Arrendamientos anuales: No especificado.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Por otro lado, un <strong>inquilino puede rescindir un contrato de arrendamiento antes de la fecha de vencimiento en los siguientes casos<\/strong>:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El inquilino va a cumplir el servicio militar activo.&nbsp;<\/li>\n\n\n\n<li>La vivienda es inhabitable.&nbsp;<\/li>\n\n\n\n<li>El propietario toma represalias o acosa al inquilino.&nbsp;<\/li>\n\n\n\n<li>Hab\u00eda una cl\u00e1usula de rescisi\u00f3n anticipada en el contrato.&nbsp;<\/li>\n\n\n\n<li>Aunque los derechos del inquilino te permiten rescindir anticipadamente el contrato de alquiler de una unidad, es posible que tengas que pagar el importe total del plazo.&nbsp;<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Desahucios&nbsp;<\/h3>\n\n\n\n<p>Un propietario puede desahuciar a su inquilino por muchas razones; entre ellas por:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Incumplimiento del contrato de alquiler.&nbsp;<\/li>\n\n\n\n<li>Actividad delictiva.&nbsp;<\/li>\n\n\n\n<li>Falta de pago.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>En estos casos, el propietario puede dar un aviso de tres d\u00edas al inquilino para que pague o abandone la vivienda. Si el contrato no estaba escrito, el inquilino puede recibir un preaviso de hasta tres meses, seg\u00fan la norma federal. Sin embargo, los inquilinos a voluntad tienen derecho a un preaviso m\u00ednimo de 30 d\u00edas o de 60 d\u00edas si llevan alquilando m\u00e1s de un a\u00f1o.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Derechos del arrendador a entrar en tu propiedad en CA<\/h3>\n\n\n\n<p>Un propietario puede entrar en tu propiedad privada si lo desea. Sin embargo, est\u00e1n obligados a notificarte 24 horas antes de entrar y pueden dar este preaviso de la forma que consideren oportuna.&nbsp;<\/p>\n\n\n\n<p>Por otra parte, ambas partes pueden programar una visita en horario comercial para evitar problemas. Sin embargo, si el propietario debe entrar como medida de emergencia, podr\u00e1 entrar sin previo aviso.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Informaci\u00f3n obligatoria&nbsp;<\/h3>\n\n\n\n<p>Conforme las leyes y derechos de inquilinos, el arrendador debe proporcionar al inquilino cinco avisos obligatorios, como los siguientes:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Aviso sobre pintura a base de plomo para viviendas construidas antes de 1978.&nbsp;<\/li>\n\n\n\n<li>Infestaciones de chinches.&nbsp;<\/li>\n\n\n\n<li>Presencia de moho.&nbsp;<\/li>\n\n\n\n<li>Medidas de control de plagas.&nbsp;<\/li>\n\n\n\n<li>Uso de los servicios p\u00fablicos.&nbsp;<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-group has-white-background-color has-background is-vertical is-content-justification-center is-layout-flex wp-container-core-group-is-layout-1 wp-block-group-is-layout-flex\">\n<p class=\"has-text-align-center\" style=\"font-size:24px\"><strong>\u00bfNecesitas m\u00e1s asesor\u00eda personalizada y GRATUITA? <\/strong>&nbsp;<\/p>\n\n\n\n<p>En Cost-U-Less te protegemos en cada momento de tu vida y siempre te brindamos los mejores consejos e informaci\u00f3n actualizada. Por ejemplo, si vas a mudarte al sur del estado, te revelamos <a href=\"https:\/\/www.costulessseguros.com\/blog\/como-es-vivir-en-san-diego-california\/\" target=\"_blank\" rel=\"noreferrer noopener\">c\u00f3mo es vivir en San Diego<\/a>. Y tambi\u00e9n te brindamos el mejor seguro de inquilinos barato&nbsp;en California. Ll\u00e1manos al\u202f <a href=\"tel:800-649-5295\">800-649-5295<\/a> o\u202f<a href=\"https:\/\/www.costulessseguros.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">cotiza en l\u00ednea<\/a>.&nbsp;<\/p>\n\n\n\n<p><\/p>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-2.jpg\" alt=\"Mujer preocupada por no conocer los derechos de los inquilinos en California\" class=\"wp-image-7831\" srcset=\"https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-2.jpg 1000w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-2-300x200.jpg 300w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-2-768x512.jpg 768w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-2-390x260.jpg 390w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-2-270x180.jpg 270w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-2-780x520.jpg 780w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-2-540x360.jpg 540w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-2-280x187.jpg 280w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-2-240x160.jpg 240w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-2-560x374.jpg 560w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-2-480x320.jpg 480w, https:\/\/www.costulessseguros.com\/blog\/wp-content\/uploads\/sites\/4\/2024\/03\/derechos-de-los-inquilinos-en-California-2-720x480.jpg 720w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Importancia de los derechos de los inquilinos en California&nbsp;<\/h2>\n\n\n\n<p>Las leyes de propietario-inquilino pueden ser confusas si est\u00e1s alquilando una vivienda por primera vez en California, donde la ley de bienes ra\u00edces est\u00e1 severamente regulada.&nbsp;<\/p>\n\n\n\n<p><strong>\u00bfPara qu\u00e9 sirven los <\/strong><strong>derechos de los inquilinos en California<\/strong><strong>?<\/strong> Estas leyes sirven para garantizar que se respeten las condiciones de pago de las personas que rentan en el estado. Adem\u00e1s de garantizar una vivienda segura y en buen estado sin importar el g\u00e9nero y procedencia.&nbsp;<\/p>\n\n\n\n<p>En resumen, las leyes inmobiliarias de control de alquileres existen para intentar resolver la crisis de la vivienda en California. Pero ten en cuenta que estas medidas no anulan las de las ciudades que ya tienen leyes de control, como San Francisco, Los \u00c1ngeles o San Jos\u00e9.&nbsp;<\/p>\n\n\n\n<p>Si est\u00e1s <a href=\"https:\/\/www.costulessseguros.com\/blog\/consejos-para-encontrar-casas-en-renta-en-los-angeles-california-en-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\">rentando una casa en Los \u00c1ngeles en 2024<\/a> o necesitas m\u00e1s informaci\u00f3n, consulta a un agente inmobiliario o a un abogado.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Preguntas frecuentes sobre los derechos de los inquilinos en CA&nbsp;<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 incluyen las leyes de propietario-inquilino?&nbsp;<\/h3>\n\n\n\n<p>Los derechos de los inquilinos en CA incluyen pol\u00edticas de control de alquileres, restricciones, limitaciones y otras pol\u00edticas diversas. Si bien es cierto que deben seguirse algunas directrices generales en un contrato de alquiler en California, <strong>algunas ciudades tienen sus propias normativas<\/strong>.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfTienen los caseros de CA que pagar intereses por las fianzas?&nbsp;<\/h3>\n\n\n\n<p><strong>Ninguna ley estatal obliga a los propietarios a pagar intereses sobre los dep\u00f3sitos de garant\u00eda<\/strong>. Sin embargo, las leyes locales (las aprobadas por una ciudad o condado) pueden exigir intereses.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfEl propietario puede cobrarme tasas de limpieza no reembolsables? \u00bfTarifas por mascotas?&nbsp;<\/h3>\n\n\n\n<p>No. Todas las cuotas de limpieza y de mascotas hacen parte del dep\u00f3sito de seguridad, y el total de cualquier cuota (ya sea que se llamen cuotas de mascotas, cuotas de limpieza o dep\u00f3sito de seguridad) no debe ser mayor que el dep\u00f3sito de seguridad m\u00e1ximo aplicable.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Estas tasas son reembolsables con arreglo a las mismas normas que se aplican a los dep\u00f3sitos de seguridad en general. Ten en cuenta que algunos propietarios pueden cobrar un alquiler adicional por tu mascota, que no se considera un dep\u00f3sito ni una cuota por mascota.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfCu\u00e1nto tiempo tienen los caseros de CA para devolver un dep\u00f3sito de seguridad?&nbsp;<\/h3>\n\n\n\n<p>Los propietarios de California tienen 21 d\u00edas naturales despu\u00e9s de que el inquilino haya desocupado las instalaciones para proporcionar al inquilino una declaraci\u00f3n detallada que indique el monto y el uso del dep\u00f3sito de seguridad y para devolver cualquier porci\u00f3n restante del dep\u00f3sito de seguridad.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Encuentra un seguro de inquilinos en California con Cost-U-Less&nbsp;<\/h2>\n\n\n\n<p>Ahora que conoces los derechos de los inquilinos en California, puedes respirar tranquilo y exigir que se respeten tus derechos. Pero no olvides que algunos arrendatarios te pueden solicitar un <a href=\"https:\/\/www.costulessseguros.com\/productos-de-seguros\/seguro-de-inquilinos\/\" target=\"_blank\" rel=\"noreferrer noopener\">seguro de inquilinos<\/a> que proteja tus propias pertenencias y ciertos da\u00f1os por accidentes como una fuga, un incendio o un robo.&nbsp;<\/p>\n\n\n\n<p>Ll\u00e1manos al\u202f<a href=\"tel:800-649-5295\">800-649-5295<\/a>, habla con un agente,\u202f<a href=\"https:\/\/www.costulessseguros.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">cotiza en l\u00ednea<\/a> o vis\u00edtanos en una\u202f<a href=\"https:\/\/www.costulessseguros.com\/recursos\/oficinas-de-seguros\/\" target=\"_blank\" rel=\"noreferrer noopener\">oficina<\/a>\u202fcerca de ti para encontrar una p\u00f3liza que proteja ante cualquier incidente.\u202f&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si est\u00e1s por rentar es importante que conozcas los derechos de los inquilinos en California para evitar abusos de parte del propietario. Seg\u00fan las leyes del estado sobre propietarios e inquilinos, al rentar tienes derecho a:&nbsp; Por ejemplo, la Ley de Protecci\u00f3n de inquilinos de 2019, exige que los propietarios tengan una raz\u00f3n justificada para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7830,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[703],"tags":[],"class_list":["post-7828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mi-seguro-de-renta"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.costulessseguros.com\/blog\/wp-json\/wp\/v2\/posts\/7828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costulessseguros.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costulessseguros.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costulessseguros.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costulessseguros.com\/blog\/wp-json\/wp\/v2\/comments?post=7828"}],"version-history":[{"count":11,"href":"https:\/\/www.costulessseguros.com\/blog\/wp-json\/wp\/v2\/posts\/7828\/revisions"}],"predecessor-version":[{"id":8503,"href":"https:\/\/www.costulessseguros.com\/blog\/wp-json\/wp\/v2\/posts\/7828\/revisions\/8503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costulessseguros.com\/blog\/wp-json\/wp\/v2\/media\/7830"}],"wp:attachment":[{"href":"https:\/\/www.costulessseguros.com\/blog\/wp-json\/wp\/v2\/media?parent=7828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costulessseguros.com\/blog\/wp-json\/wp\/v2\/categories?post=7828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costulessseguros.com\/blog\/wp-json\/wp\/v2\/tags?post=7828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}